﻿


{"id":6043,"date":"2009-04-21T17:23:34","date_gmt":"2009-04-21T16:23:34","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=6043"},"modified":"2009-04-21T17:26:31","modified_gmt":"2009-04-21T16:26:31","slug":"ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/","title":{"rendered":"Ucraina, adozioni: verso un sistema di accordi bilaterali"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-6045\" title=\"primo-piano-26-marzo1\" src=\"https:\/\/www.aibi.it\/ita\/images\/primo-piano-26-marzo1.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Promuovere le adozioni internazionali solo con i Paesi che stipuleranno un <strong>Accordo bilaterale con l&#8217;Ucraina<\/strong>. E&#8217; questa la proposta avanzata lo scorso 6 aprile da due deputate, Eugenja Suslova (Blocco Timoschenko) e Ekaterina Lukyanova (Nostra Ukraina), ora <strong>al vaglio del Parlamento ucraino. <\/strong><\/p>\n<p>Se il progetto di legge di Suslova e Lukyanova verr\u00e0 approvato, sar\u00e0 necessaria una <strong>modifica al Codice di Famiglia<\/strong> per incentivare la realizzazione di Accordi bilaterali con i governi dei Paesi di accoglienza dei minori ucraini.<\/p>\n<p>Il sito del Ministero della Famiglia ucraino, che riporta la notizia, parla di un cambiamento necessario del Codice nella parte relativa alle adozioni internazionali. La modifica sarebbe motivata da un lato dal sostanziale miglioramento delle misure di protezione dell&#8217;infanzia abbandonata nel Paese e dall&#8217;altro dalla debolezza del sistema di controlli e verifiche sull&#8217;attivit\u00e0 degli operatori che realizzano le adozioni internazionali.<\/p>\n<p>Nell&#8217;arco del 2008 sono stati adottati pi\u00f9 di <strong>2000 bambini dalle famiglie ucraine<\/strong>, mentre tre anni fa erano circa 1000. Nelle stesso anno le famiglie affidatarie e le Case famiglia hanno dato accoglienza a 2500 bambini, un numero 20 volte pi\u00f9 grande rispetto a quello del 2004. Con <strong>l&#8217;adozione internazionale<\/strong> nel 2008 hanno trovato <strong>una famiglia 1183 minori ucraini.<\/strong><\/p>\n<p>La proposta delle due parlamentari \u00e8 in linea con la politica promossa dallo stesso Ministro della Famiglia <strong>Yuri Pavlenko<\/strong> che, durante una Conferenza stampa tenutasi lo scorso febbraio, aveva parlato di una nuova misura a sostegno dell&#8217;adozione nazionale in base alla quale le coppie ucraine che adotteranno un bambino riceveranno dal Governo un assegno di 12mila grivne (pari a 1.100 euro).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promuovere le adozioni internazionali solo con i Paesi che stipuleranno un Accordo bilaterale con l&rsquo;Ucraina. E&rsquo; questa la proposta avanzata lo scorso 6 aprile da due deputate, Eugenja Suslova (Blocco Timoschenko) e Ekaterina Lukyanova (Nostra Ukraina), ora al vaglio del Parlamento ucraino. Se il progetto di legge di Suslova e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-6043","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ucraina, adozioni: verso un sistema di accordi bilaterali - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ucraina, adozioni: verso un sistema di accordi bilaterali\" \/>\n<meta property=\"og:description\" content=\"Promuovere le adozioni internazionali solo con i Paesi che stipuleranno un Accordo bilaterale con l&rsquo;Ucraina. E&rsquo; questa la proposta avanzata lo scorso 6 aprile da due deputate, Eugenja Suslova (Blocco Timoschenko) e Ekaterina Lukyanova (Nostra Ukraina), ora al vaglio del Parlamento ucraino. Se il progetto di legge di Suslova e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-21T16:23:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-04-21T16:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/primo-piano-26-marzo1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Ucraina, adozioni: verso un sistema di accordi bilaterali\",\"datePublished\":\"2009-04-21T16:23:34+00:00\",\"dateModified\":\"2009-04-21T16:26:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/\"},\"wordCount\":262,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/primo-piano-26-marzo1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/\",\"name\":\"Ucraina, adozioni: verso un sistema di accordi bilaterali - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/primo-piano-26-marzo1.jpg\",\"datePublished\":\"2009-04-21T16:23:34+00:00\",\"dateModified\":\"2009-04-21T16:26:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/primo-piano-26-marzo1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/primo-piano-26-marzo1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ucraina, adozioni: verso un sistema di accordi bilaterali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ucraina, adozioni: verso un sistema di accordi bilaterali - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/","og_locale":"it_IT","og_type":"article","og_title":"Ucraina, adozioni: verso un sistema di accordi bilaterali","og_description":"Promuovere le adozioni internazionali solo con i Paesi che stipuleranno un Accordo bilaterale con l&rsquo;Ucraina. E&rsquo; questa la proposta avanzata lo scorso 6 aprile da due deputate, Eugenja Suslova (Blocco Timoschenko) e Ekaterina Lukyanova (Nostra Ukraina), ora al vaglio del Parlamento ucraino. Se il progetto di legge di Suslova e [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2009-04-21T16:23:34+00:00","article_modified_time":"2009-04-21T16:26:31+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/primo-piano-26-marzo1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Ucraina, adozioni: verso un sistema di accordi bilaterali","datePublished":"2009-04-21T16:23:34+00:00","dateModified":"2009-04-21T16:26:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/"},"wordCount":262,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/primo-piano-26-marzo1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/","url":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/","name":"Ucraina, adozioni: verso un sistema di accordi bilaterali - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/primo-piano-26-marzo1.jpg","datePublished":"2009-04-21T16:23:34+00:00","dateModified":"2009-04-21T16:26:31+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/primo-piano-26-marzo1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/primo-piano-26-marzo1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ucraina-adozioni-verso-un-sistema-di-accordi-bilaterali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Ucraina, adozioni: verso un sistema di accordi bilaterali"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:23:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/6043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=6043"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/6043\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=6043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=6043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=6043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}