﻿


{"id":60703,"date":"2013-05-30T09:29:04","date_gmt":"2013-05-30T07:29:04","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=60703"},"modified":"2013-10-18T12:59:52","modified_gmt":"2013-10-18T10:59:52","slug":"roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/","title":{"rendered":"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia"},"content":{"rendered":"<p>Valle Sabbia<\/p>\n<p>Centro servizi alla famiglia<\/p>\n<p>17 ottobre ore 18.00<\/p>\n<p>presso Auditorium comunale, Via Verdi &#8211; Ro\u00e8 Volciano<\/p>\n<p><strong>L\u2019INAUGURAZIONE \u00c8 APERTA A TUTTE LE FAMIGLIE<\/strong><\/p>\n<p>verranno presentati i servizi disponibili per il supporto alle famiglie e ai minori, tra cui:<\/p>\n<p>SUPPORTO SCOLASTICO<\/p>\n<p>rivolto ai bambini<\/p>\n<p>LABORATORI ESPRESSIVI<\/p>\n<p>per bambini<\/p>\n<p>SPORTELLO DI SUPPORTO ALLA GENITORIALIT\u00c0<\/p>\n<p>(biologica, affidataria, adottiva)<\/p>\n<p>PROSSIMIT\u00c0 FAMILIARE<\/p>\n<p>Villanuova sul Clisi Comunit\u00e0 Montana di Valle Sabbia Vobarno Ro\u00e8<\/p>\n<p>&nbsp;<\/p>\n<p>Troverete le seguenti attivit\u00e0 e servizi gratuiti:<\/p>\n<p>LABORATORIO ESPRESSIVO<\/p>\n<p>per i bambini\/e della SCUOLA PRIMARIA<\/p>\n<p>il MARTEDI pomeriggio dalle 14.30 alle 16.00<\/p>\n<p>per i ragazzi\/della SCUOLA SECONDARIA di 1\u00b0 grado<\/p>\n<p>il MARTEDI pomeriggio dalle 16.00 alle 17.30<\/p>\n<p>SPAZIO COMPITI<\/p>\n<p>per i bambini\/e della SCUOLA PRIMARIA<\/p>\n<p>il GIOVEDI dalle 14.30 alle 17.30<\/p>\n<p>per i ragazzi\/della SCUOLA SECONDARIA di 1\u00b0 grado<\/p>\n<p>VENERDI pomeriggio dalle 14.30 alle 17.30<\/p>\n<p>SPORTELLO INFORMATIVO ACCOGLIENZA FAMILIARE E ADOZIONE<\/p>\n<p>per tutte le famiglie del Distretto 12<\/p>\n<p>il LUNEDI dalle 14.00 alle 16.00 e il GIOVEDI dalle 10.00 alle 12.00<\/p>\n<p>SPORTELLO PEDAGOGICO PER FAMIGLIE<\/p>\n<p>per tutte le famiglie del Distretto 12 con appuntamento<\/p>\n<p>il MERCOLEDI dalle 14.00 alle 16.00 e il VENERDI dalle 10.00 alle 12.00<\/p>\n<p>DOVE?<\/p>\n<p>Via L.Ragazzo 21 Roe\u2019volciano (BS)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per presentare i servizi disponibili per il supporto alle famiglie e ai minori<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-60703","post","type-post","status-publish","format-standard","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia\" \/>\n<meta property=\"og:description\" content=\"Per presentare i servizi disponibili per il supporto alle famiglie e ai minori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-30T07:29:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-10-18T10:59:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia\",\"datePublished\":\"2013-05-30T07:29:04+00:00\",\"dateModified\":\"2013-10-18T10:59:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\\\/\"},\"wordCount\":184,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\\\/\",\"name\":\"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2013-05-30T07:29:04+00:00\",\"dateModified\":\"2013-10-18T10:59:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia","og_description":"Per presentare i servizi disponibili per il supporto alle famiglie e ai minori","og_url":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2013-05-30T07:29:04+00:00","article_modified_time":"2013-10-18T10:59:52+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia","datePublished":"2013-05-30T07:29:04+00:00","dateModified":"2013-10-18T10:59:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/"},"wordCount":184,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/","url":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/","name":"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2013-05-30T07:29:04+00:00","dateModified":"2013-10-18T10:59:52+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-17-ottobre-inaugurazione-centro-servizi-alla-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"Ro\u00e8 Volciano, 17 ottobre. Inaugurazione Centro Servizi alla Famiglia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:23:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/60703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=60703"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/60703\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=60703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=60703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=60703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}