﻿


{"id":71237,"date":"2014-02-27T16:22:46","date_gmt":"2014-02-27T15:22:46","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=71237"},"modified":"2014-02-27T16:57:59","modified_gmt":"2014-02-27T15:57:59","slug":"palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/","title":{"rendered":"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/palajonio\/\" rel=\"attachment wp-att-71238\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-71238 alignleft\" style=\"margin: 5px;\" alt=\"PALAJONIO\" src=\"https:\/\/www.aibi.it\/ita\/images\/PALAJONIO.jpg\" width=\"200\" height=\"200\" data-id=\"71238\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/PALAJONIO.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/PALAJONIO-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Dormono su brandine allineate sul campo da gioco, mangiano pasti freddi, trascorrono notti intere all\u2019umidit\u00e0, in un luogo costruito per fare sport e non per piangere ripensando alla propria terra di origine. Sono i giovani migranti che, dopo essere sbarcati sulle coste italiane, <b>vengono trasferiti nei centri di prima accoglienza improvvisati<\/b>, come quello allestito al <b>Palajonio di Augusta<\/b>, in provincia di Siracusa.<\/p>\n<p>I minori stranieri non accompagnati, dal loro arrivo e presa in carico da parte del Comune, <b>dovrebbero rimanere al Palajonio solo un paio di giorni<\/b>, prima di essere trasferiti nei centri di accoglienza e poi nelle comunit\u00e0 alloggio distribuite su tutto il territorio italiano e non solo siciliano. Invece <b>i tempi si allungano a dismisura<\/b> e le comunit\u00e0 ospitanti sono perennemente al collasso.<\/p>\n<p>In questo modo la costa orientale della Sicilia <b>si trova costantemente a fare fronte alla marea umana<\/b> che quasi quotidianamente si riversa sulle banchine dei suoi porti. L\u2019impegno della popolazione locale \u00e8 notevole, ma <b>le sue forze rischiano di non poter reggere a lungo<\/b>. I numeri degli arrivi sono altissimi e non si fa in tempo a trovare una sistemazione per chi sbarca che immediatamente si aggiungono altre migliaia di persone da ospitare.<\/p>\n<p>Ne consegue che l\u2019assistenza igienico sanitaria che si pu\u00f2 garantire a questi giovanissimi non \u00e8 adeguata, ma <i>\u201csi pu\u00f2 e si deve definirla disumana\u201d<\/i> secondo una volontaria della parrocchia di san Giuseppe Innografo di Augusta. <i>\u201cLa struttura sportiva viene contemporaneamente usata da ragazzi augustani che si allenano per il campionato <\/i>\u2013 continua \u2013<i>. E mentre vedo i volontari sacrificarsi e mettere a rischio la loro salute per aiutare questi giovani e farli sentire meno abbandonati, sento forte la solitudine a cui le istituzioni condannano non solo i profughi, ma anche chi ha nel cuore il forte desiderio di accoglierli\u201d<\/i>.<\/p>\n<p><b>Tutto l\u2019onere dell\u2019accoglienza ricade quindi sui sindaci<\/b>, alle prese con le difficolt\u00e0 dei bilanci comunali. <i>\u201cSiamo pienamente consapevoli che il Palajonio non \u00e8 adeguato <\/i>\u2013 afferma il commissario del Comune di Augusta, il prefetto <b>Maria Carmela Librizzi<\/b> \u2013<i>, ma l\u2019alternativa sarebbe stata lasciare questi ragazzi per strada. Stiamo cercando strutture alternative, ma l\u2019amministrazione \u00e8 in dissesto\u201d<\/i>.<\/p>\n<p>Tutto lascia ipotizzare che l\u2019emergenza non si fermer\u00e0. Per questo motivo l\u2019amministrazione comunale di Augusta ha scritto al Ministero del lavoro e delle politiche sociali, informando anche il Ministero dell\u2019interno, <i>\u201cperch\u00e9 si crei una cabina di regia centrale, che possa regolamentare lo smistamento dei minori in comunit\u00e0 del territorio nazionale\u201d<\/i>.<\/p>\n<p>Nel frattempo, un recente rapporto elaborato nell\u2019ambito del progetto europeo \u201cImpact\u201d ha inserito anche i minori stranieri non accompagnati in transito in Italia <b>tra le principali vittime di tratta e sfruttamento minorile<\/b>, conseguenza delle lacune nei sistemi di welfare e protezione dell\u2019infanzia. Determinante per garantire maggiore protezione a questi giovanissimi \u00e8 il ruolo dei volontari e la loro formazione. Anche con questo scopo, a Siracusa, <b>\u00e8 nata l\u2019associazione \u201cAccoglieRete\u201d<\/b>, una formazione di 75 tra tutor e volontari, pronti a prendersi cura dei migranti soli tra i 10 e i 17 anni.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Avvenire (27 febbraio 2014)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dormono su brandine allineate sul campo da gioco, mangiano pasti freddi, trascorrono notti intere all\u2019umidit\u00e0. Sono i giovani migranti che, dopo essere sbarcati sulle coste italiane,\u00a0<b>vengono trasferiti nei centri di prima accoglienza improvvisati<\/b>, come quello allestito al\u00a0<b>Palajonio di Augusta<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><a href=\"https:\/\/www.aibi.it\/ita\/papa-francesco-frutto-della-guerra-sono-i-bambini-affamati-mentre-i-fabbricanti-di-armi-festeggiano\/\">Leggi anche Papa Francesco: &#8220;Frutto della guerra sono bambini affamati, mentre fabbricanti di armi festeggiano&#8221; &gt;&gt;<\/a><\/strong> |\u00a0<strong><a href=\"https:\/\/www.aibi.it\/ita\/sono-1085-i-migranti-sbarcati-in-sicilia-nellultimo-week-end-596-in-meno-di-un-giorno\/\">Sono 1085 i migranti sbarcati in Sicilia nell&#8217;ultimo week end &gt;&gt;<\/a>\u00a0<\/strong><\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-71237","post","type-post","status-publish","format-standard","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti\" \/>\n<meta property=\"og:description\" content=\"Dormono su brandine allineate sul campo da gioco, mangiano pasti freddi, trascorrono notti intere all\u2019umidit\u00e0. Sono i giovani migranti che, dopo essere sbarcati sulle coste italiane,\u00a0vengono trasferiti nei centri di prima accoglienza improvvisati, come quello allestito al\u00a0Palajonio di Augusta.  &nbsp;  Leggi anche Papa Francesco: &quot;Frutto della guerra sono bambini affamati, mentre fabbricanti di armi festeggiano&quot; &gt;&gt; |\u00a0Sono 1085 i migranti sbarcati in Sicilia nell&#039;ultimo week end &gt;&gt;\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-27T15:22:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-27T15:57:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/PALAJONIO.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti\",\"datePublished\":\"2014-02-27T15:22:46+00:00\",\"dateModified\":\"2014-02-27T15:57:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/\"},\"wordCount\":508,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/PALAJONIO.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/\",\"name\":\"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/PALAJONIO.jpg\",\"datePublished\":\"2014-02-27T15:22:46+00:00\",\"dateModified\":\"2014-02-27T15:57:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/PALAJONIO.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/PALAJONIO.jpg\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/","og_locale":"it_IT","og_type":"article","og_title":"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti","og_description":"Dormono su brandine allineate sul campo da gioco, mangiano pasti freddi, trascorrono notti intere all\u2019umidit\u00e0. Sono i giovani migranti che, dopo essere sbarcati sulle coste italiane,\u00a0vengono trasferiti nei centri di prima accoglienza improvvisati, come quello allestito al\u00a0Palajonio di Augusta.  &nbsp;  Leggi anche Papa Francesco: \"Frutto della guerra sono bambini affamati, mentre fabbricanti di armi festeggiano\" &gt;&gt; |\u00a0Sono 1085 i migranti sbarcati in Sicilia nell'ultimo week end &gt;&gt;\u00a0","og_url":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2014-02-27T15:22:46+00:00","article_modified_time":"2014-02-27T15:57:59+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/PALAJONIO.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti","datePublished":"2014-02-27T15:22:46+00:00","dateModified":"2014-02-27T15:57:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/"},"wordCount":508,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/PALAJONIO.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/","url":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/","name":"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/PALAJONIO.jpg","datePublished":"2014-02-27T15:22:46+00:00","dateModified":"2014-02-27T15:57:59+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/PALAJONIO.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/PALAJONIO.jpg","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/palajonio-di-augusta-impossibile-garantire-accoglienza-decorosa-ai-giovani-migranti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Palajonio di Augusta: impossibile garantire accoglienza decorosa ai giovani migranti"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:19:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/71237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=71237"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/71237\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=71237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=71237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=71237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}