﻿


{"id":85833,"date":"2014-09-15T16:24:25","date_gmt":"2014-09-15T14:24:25","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=85833"},"modified":"2014-09-16T20:18:33","modified_gmt":"2014-09-16T18:18:33","slug":"come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/","title":{"rendered":"Come rispondere al  Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-80915 alignleft\" style=\"margin: 5px;\" alt=\"misna4\" src=\"https:\/\/www.aibi.it\/ita\/images\/misna41.jpg\" width=\"200\" height=\"200\" data-id=\"80915\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/misna41.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/misna41-150x150.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/misna41-55x55.jpg 55w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Mentre 200 esseri umani potrebbero essere stati inghiottiti dal mare al largo della Libia e mentre lo Stato Italiano da una parte e le associazioni di volontariato dall\u2019altro cercano a fatica di soccorrere quante pi\u00f9 persone possibile tra quelle che tentano i viaggi della disperazione, c\u2019\u00e8 qualcuno che non trova di meglio da fare che <b>inscenare siparietti mediatici<\/b> <b>per protestare contro l\u2019arrivo di uno sparuto gruppo di migranti.<\/b><\/p>\n<p>L\u2019ideatore della colorita iniziativa \u00e8 <b>Daniele Baglione, sindaco leghista di Gattinara<\/b>, comune del Vercellese. Appreso della presenza nel suo territorio di <b>6 (sei!!!) profughi provenienti dal Gambia<\/b>, il primo cittadino ha messo in atto una protesta alquanto singolare: <b>ha indossato la fascia da lutto al braccio<\/b>, imitato dal vicesindaco e da alcuni assessori. E non si \u00e8 fermato qui: <b>ha listato a lutto anche le bandiere del palazzo del Municipio<\/b>.<\/p>\n<p>Il motivo? <i>\u201cL\u2019ho fatto non nei confronti degli immigrati<\/i> \u2013 ha spiegato Baglione \u2013<i>, ma di un sistema che non tutela i propri cittadini e fornisce garanzie illusorie a chi giunge in Italia\u201d<\/i>. Non contento, il sindaco ha promosso una raccolta di firme, a cui ha aderito un migliaio di cittadini, <b>affinch\u00e9 non si utilizzi il presidio ospedaliero per l\u2019accoglienza dei migranti<\/b>, <i>\u201cma si scelgano luoghi pi\u00f9 adatti per accogliere queste persone\u201d<\/i>, ha detto il primo cittadino di Gattinara. Che ha lanciato anche un\u2019altra idea decisamente \u201ccuriosa\u201d: <i>\u201cI cittadini che vengono in municipio a chiederci aiuto economico o un lavoro <\/i>\u2013 ha annunciato \u2013 <i>potranno compilare un modulo per chiedere allo Stato di essere considerati rifugiati politici in Italia\u201d<\/i>.<\/p>\n<p>I sei migranti giunti a Gattinara sono stati inizialmente sistemati nel presidio sanitario della cittadina e poi <b>trasferiti in alcune case di riposo della provincia<\/b> di Vercelli.<\/p>\n<p><b>\u201cSconcertante\u201d<\/b> \u00e8 l\u2019aggettivo con cui l\u2019assessore regionale all\u2019immigrazione <b>Monica Cerutti<\/b> ha definito l\u2019iniziativa di Baglione. <i>\u201c\u00e8 intollerabile che <b>qualcuno cerchi la ribalta mediatica sulle spalle dei profughi<\/b><\/i> \u2013 ha denunciato Cerutti \u2013<i>. Il sindaco di Gattinara <b>non sta servendo lo Stato<\/b> e neppure i suoi cittadini, <b>fomentando una pericolosa guerra tra poveri<\/b>. Sappiamo anche noi che il sistema di accoglienza dei profughi deve essere migliorato e stiamo cercando di farlo nonostante le difficolt\u00e0 oggettive\u201d.<\/i><\/p>\n<p>Difficolt\u00e0 di cui anche <b>Amici dei Bambini<\/b> \u00e8 pienamente cosciente e ha pi\u00f9 volte parlato. Per questo ritiene che <b>la replica pi\u00f9 efficace a una provocazione come quella del sindaco di Gattinara sia l\u2019accoglienza giusta<\/b>. Per tutti i migranti e in particolare per quelli pi\u00f9 indifesi: i <b>minori stranieri non accompagnati<\/b> che approdano sulle nostre coste in cerca prima di tutto di affetto.<\/p>\n<p>Per garantire loro un\u2019accoglienza giusta, Ai.Bi. ha attivato da quasi un anno il progetto <b><a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/bambini-in-alto-mare\/\">Bambini in Alto Mare<\/a><\/b>. A cui ognuno pu\u00f2 dare un contributo, <b>anche con un semplice Sostegno a Distanza<\/b>: un piccolo impegno per un grande risultato, <b>garantire ai Misna un\u2019accoglienza a misura di bambino in una delle &#8220;Case Mos\u00e8&#8221; di Ai.Bi.\u00a0<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: <a href=\"http:\/\/torino.repubblica.it\/cronaca\/2014\/09\/11\/news\/sindaco_con_il_braccio_al_lutto_per_l_arrivo_di_sei_profughi-95518070\/\">la Repubblica<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mentre 200 esseri umani potrebbero essere stati inghiottiti dal mare al largo della Libia, c\u2019\u00e8 qualcuno che non trova di meglio da fare che\u00a0<b>inscenare siparietti mediatici<\/b>\u00a0<b>per protestare contro l\u2019arrivo di uno sparuto gruppo di migranti.<\/b><\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114,66],"tags":[],"class_list":["post-85833","post","type-post","status-publish","format-standard","category-aibinews","category-bambini-in-alto-mare","category-sad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi?  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi?\" \/>\n<meta property=\"og:description\" content=\"Mentre 200 esseri umani potrebbero essere stati inghiottiti dal mare al largo della Libia, c\u2019\u00e8 qualcuno che non trova di meglio da fare che\u00a0inscenare siparietti mediatici\u00a0per protestare contro l\u2019arrivo di uno sparuto gruppo di migranti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-15T14:24:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-09-16T18:18:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/misna41.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi?\",\"datePublished\":\"2014-09-15T14:24:25+00:00\",\"dateModified\":\"2014-09-16T18:18:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/\"},\"wordCount\":496,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/misna41.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\",\"Sostegno a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/\",\"name\":\"Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/misna41.jpg\",\"datePublished\":\"2014-09-15T14:24:25+00:00\",\"dateModified\":\"2014-09-16T18:18:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/misna41.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/misna41.jpg\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi?  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/","og_locale":"it_IT","og_type":"article","og_title":"Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi?","og_description":"Mentre 200 esseri umani potrebbero essere stati inghiottiti dal mare al largo della Libia, c\u2019\u00e8 qualcuno che non trova di meglio da fare che\u00a0inscenare siparietti mediatici\u00a0per protestare contro l\u2019arrivo di uno sparuto gruppo di migranti.","og_url":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2014-09-15T14:24:25+00:00","article_modified_time":"2014-09-16T18:18:33+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/misna41.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi?","datePublished":"2014-09-15T14:24:25+00:00","dateModified":"2014-09-16T18:18:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/"},"wordCount":496,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/misna41.jpg","articleSection":["AiBiNews","Bambini in alto mare","Sostegno a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/","url":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/","name":"Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/misna41.jpg","datePublished":"2014-09-15T14:24:25+00:00","dateModified":"2014-09-16T18:18:33+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/misna41.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/misna41.jpg","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/come-rispondere-al-sindaco-con-il-lutto-al-braccio-per-larrivo-di-sei-profughi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Come rispondere al Sindaco con il lutto al braccio per l\u2019arrivo di sei profughi?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:20:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/85833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=85833"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/85833\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=85833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=85833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=85833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}